{"id":2052,"date":"2019-01-07T20:44:02","date_gmt":"2019-01-07T19:44:02","guid":{"rendered":"https:\/\/www.appointmed.com\/blog\/?p=2052"},"modified":"2021-07-06T12:59:00","modified_gmt":"2021-07-06T11:59:00","slug":"aenderungen-vom-7-jaenner-2019","status":"publish","type":"post","link":"https:\/\/www.appointmed.com\/blog\/aenderungen-vom-7-jaenner-2019","title":{"rendered":"\u00c4nderungen vom 7. J\u00e4nner 2019"},"content":{"rendered":"<h3 class=\"changelogNew\">Neu<\/h3>\n<ul>\n<li>\n<h4>Termine mit Google Kalender synchronisieren<\/h4>\n<div id=\"attachment_2056\" class=\"wp-caption alignnone\" style=\"width: 770px\"><a href=\"https:\/\/www.appointmed.com\/blog\/wp-content\/uploads\/2019\/01\/google-kalender-sync-appointmed.gif\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-2056\" src=\"https:\/\/www.appointmed.com\/blog\/wp-content\/uploads\/2019\/01\/google-kalender-sync-appointmed.gif\" alt=\"\" width=\"770\" height=\"479\" \/><\/a><p class=\"wp-caption-text\">Zeige Deine appointmed Termine in Deinem Google Kalender an<\/p><\/div>\n<p>Einer der h\u00e4ufigsten Verbesserungsw\u00fcnsche ist nun umgesetzt. Verkn\u00fcpfe Deinen appointmed Kalender mit Deinem Google Konto und alle Termine werden automatisch auch in Google angezeigt. Aus Datenschutzgr\u00fcnden werden die Namen der Patienten nicht \u00fcbertragen. Im ersten Schritt handelt es sich bei dieser Funktion um einen 1-Weg Sync. Das hei\u00dft, dass \u00c4nderungen im Google Kalender nicht zur\u00fcck in Deinen appointmed Kalender \u00fcbertragen werden.<\/p>\n<p>Infos zur <a href=\"https:\/\/intercom.help\/appointmed\/de\/articles\/2619676-verknupfe-deinen-appointmed-kalender-mit-google-kalender\" target=\"_blank\" rel=\"noopener\">Konfiguration der Kalender Synchronisierung<\/a> findest Du im Help Center.<\/li>\n<\/ul>\n<h3 class=\"changelogImproved\">Verbesserungen<\/h3>\n<ul>\n<li>\n<h4>Erinnerung f\u00fcr Patienten bei Termin\u00e4nderungen<\/h4>\n<p>Wenn Du einen Termin im Kalender verschiebst, kannst Du den Patienten (optional) dar\u00fcber via SMS oder E-Mail informieren.<\/li>\n<li>\n<h4>Kontaktbereich in Patienten E-Mails<\/h4>\n<p>Wir haben den Kontaktbereich in Patienten E-Mails verbessert und zB die h\u00e4ufige Anzeige des Namens des Therapeuten korrigiert.<\/li>\n<\/ul>\n<h3 class=\"changelogFixed\">Fehlerbehebungen<\/h3>\n<ul style=\"line-height: normal;\">\n<li>Falsche Anzahl von Patienten im Infofeld (&#8222;XXX Patienten&#8220;) bei aktiven Filtern in der Patientenliste korrigiert.<\/li>\n<li>Fehlendes Praxislogo auf Tages-, Monats- und Jahresabschl\u00fcssen hinzugef\u00fcgt.<\/li>\n<li>Seltene, automatische Best\u00e4tigung von Terminanfragen bei der Online Buchung deaktiviert.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Neu Termine mit Google Kalender synchronisieren Einer der h\u00e4ufigsten Verbesserungsw\u00fcnsche ist nun umgesetzt. Verkn\u00fcpfe Deinen appointmed Kalender mit Deinem Google Konto und alle Termine werden automatisch auch in Google angezeigt. Aus Datenschutzgr\u00fcnden werden die Namen der Patienten nicht \u00fcbertragen. Im ersten Schritt handelt es sich bei dieser Funktion um einen 1-Weg Sync. Das hei\u00dft, dass [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2052","post","type-post","status-publish","format-standard","hentry","category-changelog"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00c4nderungen vom 7. J\u00e4nner 2019 - appointmed Updates<\/title>\n<meta name=\"description\" content=\"Neu Termine mit Google Kalender synchronisieren Einer der h\u00e4ufigsten Verbesserungsw\u00fcnsche ist nun umgesetzt. Verkn\u00fcpfe Deinen appointmed Kalender mit\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.appointmed.com\/blog\/aenderungen-vom-7-jaenner-2019\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c4nderungen vom 7. J\u00e4nner 2019\" \/>\n<meta property=\"og:description\" content=\"Neu Termine mit Google Kalender synchronisieren Einer der h\u00e4ufigsten Verbesserungsw\u00fcnsche ist nun umgesetzt. Verkn\u00fcpfe Deinen appointmed Kalender mit\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.appointmed.com\/blog\/aenderungen-vom-7-jaenner-2019\" \/>\n<meta property=\"og:site_name\" content=\"appointmed Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/appointmed\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-07T19:44:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-06T11:59:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.appointmed.com\/blog\/wp-content\/uploads\/2019\/01\/google-kalender-sync-appointmed.gif\" \/>\n<meta name=\"author\" content=\"Mario H.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@appointmed\" \/>\n<meta name=\"twitter:site\" content=\"@appointmed\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/aenderungen-vom-7-jaenner-2019#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/aenderungen-vom-7-jaenner-2019\"},\"author\":{\"name\":\"Mario H.\",\"@id\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/#\\\/schema\\\/person\\\/d94cc659b2c8eb4bcdc1182ad8e0993f\"},\"headline\":\"\u00c4nderungen vom 7. J\u00e4nner 2019\",\"datePublished\":\"2019-01-07T19:44:02+00:00\",\"dateModified\":\"2021-07-06T11:59:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/aenderungen-vom-7-jaenner-2019\"},\"wordCount\":191,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/aenderungen-vom-7-jaenner-2019#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/google-kalender-sync-appointmed.gif\",\"articleSection\":[\"Updates\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/aenderungen-vom-7-jaenner-2019#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/aenderungen-vom-7-jaenner-2019\",\"url\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/aenderungen-vom-7-jaenner-2019\",\"name\":\"\u00c4nderungen vom 7. J\u00e4nner 2019 - appointmed Updates\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/aenderungen-vom-7-jaenner-2019#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/aenderungen-vom-7-jaenner-2019#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/google-kalender-sync-appointmed.gif\",\"datePublished\":\"2019-01-07T19:44:02+00:00\",\"dateModified\":\"2021-07-06T11:59:00+00:00\",\"description\":\"Neu Termine mit Google Kalender synchronisieren Einer der h\u00e4ufigsten Verbesserungsw\u00fcnsche ist nun umgesetzt. Verkn\u00fcpfe Deinen appointmed Kalender mit\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/aenderungen-vom-7-jaenner-2019#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/aenderungen-vom-7-jaenner-2019\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/aenderungen-vom-7-jaenner-2019#primaryimage\",\"url\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/google-kalender-sync-appointmed.gif\",\"contentUrl\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/google-kalender-sync-appointmed.gif\",\"width\":1200,\"height\":747,\"caption\":\"Zeige Deine appointmed Termine in Deinem Google Kalender an\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/aenderungen-vom-7-jaenner-2019#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c4nderungen vom 7. J\u00e4nner 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/\",\"name\":\"appointmed Blog\",\"description\":\"Die unkomplizierte Praxissoftware\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/#organization\",\"name\":\"appointmed GmbH\",\"url\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/appointmed-Logo-V2-cropped-transparent.png\",\"contentUrl\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/appointmed-Logo-V2-cropped-transparent.png\",\"width\":1200,\"height\":257,\"caption\":\"appointmed GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/appointmed\",\"https:\\\/\\\/x.com\\\/appointmed\",\"https:\\\/\\\/www.instagram.com\\\/appointmed\",\"https:\\\/\\\/de.linkedin.com\\\/company\\\/appointmed\",\"https:\\\/\\\/www.youtube.com\\\/appointmed\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/#\\\/schema\\\/person\\\/d94cc659b2c8eb4bcdc1182ad8e0993f\",\"name\":\"Mario H.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c97357d58d995e44d0f1757b83b35ce370f27512c6e21c10cdb8d17c511b149c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c97357d58d995e44d0f1757b83b35ce370f27512c6e21c10cdb8d17c511b149c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c97357d58d995e44d0f1757b83b35ce370f27512c6e21c10cdb8d17c511b149c?s=96&d=mm&r=g\",\"caption\":\"Mario H.\"},\"description\":\"Neben seinem Engagement f\u00fcr diverse medizinische Gesellschaften (EUROSPINE, EFNR, spine.at), hat Mario mehrere Jahre Erfahrung im Brand Management der \u00d6sterreich Werbung gesammelt.\",\"sameAs\":[\"https:\\\/\\\/www.appointmed.com\\\/team\"],\"jobTitle\":\"CMO, Co-Founder\",\"worksFor\":\"appointmed GmbH\",\"url\":\"https:\\\/\\\/www.appointmed.com\\\/blog\\\/author\\\/mario\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00c4nderungen vom 7. J\u00e4nner 2019 - appointmed Updates","description":"Neu Termine mit Google Kalender synchronisieren Einer der h\u00e4ufigsten Verbesserungsw\u00fcnsche ist nun umgesetzt. Verkn\u00fcpfe Deinen appointmed Kalender mit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.appointmed.com\/blog\/aenderungen-vom-7-jaenner-2019","og_locale":"de_DE","og_type":"article","og_title":"\u00c4nderungen vom 7. J\u00e4nner 2019","og_description":"Neu Termine mit Google Kalender synchronisieren Einer der h\u00e4ufigsten Verbesserungsw\u00fcnsche ist nun umgesetzt. Verkn\u00fcpfe Deinen appointmed Kalender mit","og_url":"https:\/\/www.appointmed.com\/blog\/aenderungen-vom-7-jaenner-2019","og_site_name":"appointmed Blog","article_publisher":"https:\/\/www.facebook.com\/appointmed","article_published_time":"2019-01-07T19:44:02+00:00","article_modified_time":"2021-07-06T11:59:00+00:00","og_image":[{"url":"https:\/\/www.appointmed.com\/blog\/wp-content\/uploads\/2019\/01\/google-kalender-sync-appointmed.gif","type":"","width":"","height":""}],"author":"Mario H.","twitter_card":"summary_large_image","twitter_creator":"@appointmed","twitter_site":"@appointmed","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.appointmed.com\/blog\/aenderungen-vom-7-jaenner-2019#article","isPartOf":{"@id":"https:\/\/www.appointmed.com\/blog\/aenderungen-vom-7-jaenner-2019"},"author":{"name":"Mario H.","@id":"https:\/\/www.appointmed.com\/blog\/#\/schema\/person\/d94cc659b2c8eb4bcdc1182ad8e0993f"},"headline":"\u00c4nderungen vom 7. J\u00e4nner 2019","datePublished":"2019-01-07T19:44:02+00:00","dateModified":"2021-07-06T11:59:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.appointmed.com\/blog\/aenderungen-vom-7-jaenner-2019"},"wordCount":191,"commentCount":0,"publisher":{"@id":"https:\/\/www.appointmed.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.appointmed.com\/blog\/aenderungen-vom-7-jaenner-2019#primaryimage"},"thumbnailUrl":"https:\/\/www.appointmed.com\/blog\/wp-content\/uploads\/2019\/01\/google-kalender-sync-appointmed.gif","articleSection":["Updates"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.appointmed.com\/blog\/aenderungen-vom-7-jaenner-2019#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.appointmed.com\/blog\/aenderungen-vom-7-jaenner-2019","url":"https:\/\/www.appointmed.com\/blog\/aenderungen-vom-7-jaenner-2019","name":"\u00c4nderungen vom 7. J\u00e4nner 2019 - appointmed Updates","isPartOf":{"@id":"https:\/\/www.appointmed.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.appointmed.com\/blog\/aenderungen-vom-7-jaenner-2019#primaryimage"},"image":{"@id":"https:\/\/www.appointmed.com\/blog\/aenderungen-vom-7-jaenner-2019#primaryimage"},"thumbnailUrl":"https:\/\/www.appointmed.com\/blog\/wp-content\/uploads\/2019\/01\/google-kalender-sync-appointmed.gif","datePublished":"2019-01-07T19:44:02+00:00","dateModified":"2021-07-06T11:59:00+00:00","description":"Neu Termine mit Google Kalender synchronisieren Einer der h\u00e4ufigsten Verbesserungsw\u00fcnsche ist nun umgesetzt. Verkn\u00fcpfe Deinen appointmed Kalender mit","breadcrumb":{"@id":"https:\/\/www.appointmed.com\/blog\/aenderungen-vom-7-jaenner-2019#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.appointmed.com\/blog\/aenderungen-vom-7-jaenner-2019"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.appointmed.com\/blog\/aenderungen-vom-7-jaenner-2019#primaryimage","url":"https:\/\/www.appointmed.com\/blog\/wp-content\/uploads\/2019\/01\/google-kalender-sync-appointmed.gif","contentUrl":"https:\/\/www.appointmed.com\/blog\/wp-content\/uploads\/2019\/01\/google-kalender-sync-appointmed.gif","width":1200,"height":747,"caption":"Zeige Deine appointmed Termine in Deinem Google Kalender an"},{"@type":"BreadcrumbList","@id":"https:\/\/www.appointmed.com\/blog\/aenderungen-vom-7-jaenner-2019#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.appointmed.com\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00c4nderungen vom 7. J\u00e4nner 2019"}]},{"@type":"WebSite","@id":"https:\/\/www.appointmed.com\/blog\/#website","url":"https:\/\/www.appointmed.com\/blog\/","name":"appointmed Blog","description":"Die unkomplizierte Praxissoftware","publisher":{"@id":"https:\/\/www.appointmed.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.appointmed.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.appointmed.com\/blog\/#organization","name":"appointmed GmbH","url":"https:\/\/www.appointmed.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.appointmed.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.appointmed.com\/blog\/wp-content\/uploads\/2019\/08\/appointmed-Logo-V2-cropped-transparent.png","contentUrl":"https:\/\/www.appointmed.com\/blog\/wp-content\/uploads\/2019\/08\/appointmed-Logo-V2-cropped-transparent.png","width":1200,"height":257,"caption":"appointmed GmbH"},"image":{"@id":"https:\/\/www.appointmed.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/appointmed","https:\/\/x.com\/appointmed","https:\/\/www.instagram.com\/appointmed","https:\/\/de.linkedin.com\/company\/appointmed","https:\/\/www.youtube.com\/appointmed"]},{"@type":"Person","@id":"https:\/\/www.appointmed.com\/blog\/#\/schema\/person\/d94cc659b2c8eb4bcdc1182ad8e0993f","name":"Mario H.","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/c97357d58d995e44d0f1757b83b35ce370f27512c6e21c10cdb8d17c511b149c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c97357d58d995e44d0f1757b83b35ce370f27512c6e21c10cdb8d17c511b149c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c97357d58d995e44d0f1757b83b35ce370f27512c6e21c10cdb8d17c511b149c?s=96&d=mm&r=g","caption":"Mario H."},"description":"Neben seinem Engagement f\u00fcr diverse medizinische Gesellschaften (EUROSPINE, EFNR, spine.at), hat Mario mehrere Jahre Erfahrung im Brand Management der \u00d6sterreich Werbung gesammelt.","sameAs":["https:\/\/www.appointmed.com\/team"],"jobTitle":"CMO, Co-Founder","worksFor":"appointmed GmbH","url":"https:\/\/www.appointmed.com\/blog\/author\/mario"}]}},"_links":{"self":[{"href":"https:\/\/www.appointmed.com\/blog\/wp-json\/wp\/v2\/posts\/2052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.appointmed.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.appointmed.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.appointmed.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.appointmed.com\/blog\/wp-json\/wp\/v2\/comments?post=2052"}],"version-history":[{"count":0,"href":"https:\/\/www.appointmed.com\/blog\/wp-json\/wp\/v2\/posts\/2052\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.appointmed.com\/blog\/wp-json\/wp\/v2\/media?parent=2052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.appointmed.com\/blog\/wp-json\/wp\/v2\/categories?post=2052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.appointmed.com\/blog\/wp-json\/wp\/v2\/tags?post=2052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}